{"id":25870,"date":"2020-11-16T15:38:42","date_gmt":"2020-11-16T18:38:42","guid":{"rendered":"https:\/\/www.texabrasil.com.br\/condiciones-generales-de-venta\/"},"modified":"2024-08-07T11:47:38","modified_gmt":"2024-08-07T14:47:38","slug":"condiciones-generales-de-venta","status":"publish","type":"page","link":"https:\/\/www.texabrasil.com.br\/es\/condiciones-generales-de-venta\/","title":{"rendered":"Condiciones generales de venta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25870\" class=\"elementor elementor-25870 elementor-6876\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-243cc0c elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-space-between elementor-section-boxed elementor-section-height-default\" data-id=\"243cc0c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26f1cbe\" data-id=\"26f1cbe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7691b4 elementor-widget elementor-widget-spacer\" data-id=\"a7691b4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dcebe2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcebe2b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-55a79a5\" data-id=\"55a79a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecfab6c elementor-widget elementor-widget-heading\" data-id=\"ecfab6c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">Condiciones generales de venta<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6df72b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6df72b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-550cb59\" data-id=\"550cb59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e7ebb4 elementor-widget elementor-widget-spacer\" data-id=\"9e7ebb4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80d68c9 elementor-widget elementor-widget-text-editor\" data-id=\"80d68c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. DEFINICIONES<\/strong><br \/>\n<strong>FABRICANTE:<\/strong> el FABRICANTE es TEXA SpA.<br \/>\nORGANIZACI\u00d3N DE VENTAS: la parte que vende los PRODUCTOS al CLIENTE. FABRICANTE y ORGANIZACI\u00d3N DE VENTAS pueden coincidir<br \/>\nCLIENTE: la parte que compra los PRODUCTOS a la ORGANIZACI\u00d3N DE VENTAS.<br \/>\nPRODUCTOS: aquellos comercializados por la ORGANIZACI\u00d3N DE VENTAS e indicados en las CONDICIONES PARTICULARES. En cualquier caso, esto s\u00f3lo incluye los PRODUCTOS enumerados en la lista de precios de venta al p\u00fablico oficial de TEXA SpA.<br \/>\nCONDICIONES PARTICULARES: las condiciones pactadas entre la ORGANIZACI\u00d3N DE VENTAS y el CLIENTE que regulan las condiciones espec\u00edficas de compra de los PRODUCTOS.<\/p>\n<p><strong>2. ORDEN DE COMPRA, PRECIO Y CONDICIONES DE PAGO<\/strong><br \/>\nEl precio acordado se indica en las CONDICIONES PARTICULARES e incluye la suma del precio neto acordado de los PRODUCTOS, m\u00e1s los gastos accesorios. Salvo que se indique lo contrario, el IVA no est\u00e1 incluido en el precio. Cualquier gasto adicional, como gastos relacionados con el cumplimiento de normas del sistema el\u00e9ctrico, trabajos de alba\u00f1iler\u00eda, sistema de aire comprimido u otra intervenci\u00f3n necesaria para el funcionamiento de ciertos PRODUCTOS, ser\u00e1 responsabilidad del CLIENTE. Si dicho trabajo es necesario, deber\u00e1 realizarse de acuerdo con las especificaciones emitidas por el FABRICANTE.<br \/>\nEl pago deber\u00e1 realizarse conforme a los plazos establecidos en las CONDICIONES PARTICULARES o, en caso de no haberse pactado plazos, el pago se realizar\u00e1 antes de la entrega de los PRODUCTOS. El plazo de pago se considerar\u00e1 imprescindible. La ORGANIZACI\u00d3N DE VENTAS podr\u00e1 suspender la entrega de los PRODUCTOS contenidos en las \u00f3rdenes de compra confirmadas hasta el pago total por parte del CLIENTE de todos los importes adeudados. Si se pacta el pago anticipado, la ORGANIZACI\u00d3N DE VENTAS no proceder\u00e1 a la entrega de los PRODUCTOS hasta el pago total por parte del CLIENTE del pedido de compra confirmado. En caso de retraso en el pago, el CLIENTE deber\u00e1 pagar el tipo de inter\u00e9s legal, m\u00e1s el 4%, sobre el saldo pendiente, as\u00ed como los gastos que incurra para recuperar el cr\u00e9dito.<\/p>\n<p><strong>3. ENTREGA, TRANSFERENCIA DE PROPIEDAD Y ACEPTACI\u00d3N<\/strong><br \/>\nEl plazo de entrega indicado en las CONDICIONES PARTICULARES es aproximado. No obstante, si la ORGANIZACI\u00d3N DE VENTAS no comunica al CLIENTE la disponibilidad del PRODUCTO solicitado en un plazo de gracia de cuatro semanas desde el plazo de entrega indicado, el CLIENTE tendr\u00e1 derecho a cancelar el pedido mediante simple comunicaci\u00f3n escrita al VENDEDOR. ORGANIZACI\u00d3N y podr\u00e1 exigir la devoluci\u00f3n del importe pagado en concepto de dep\u00f3sito para confirmar el pedido, m\u00e1s los intereses, que se calcular\u00e1n al tipo del 4% anual.<br \/>\nLos PRODUCTOS se pueden entregar en diferentes lotes. El lugar de entrega se indica en las CONDICIONES PARTICULARES si es distinto del domicilio legal. La transferencia de propiedad de los PRODUCTOS s\u00f3lo se producir\u00e1 despu\u00e9s del pago de la totalidad del importe adeudado. Hasta ese momento, el CLIENTE no podr\u00e1 modificar los PRODUCTOS, utilizarlos como garant\u00eda ni revenderlos. La ORGANIZACI\u00d3N DE VENTAS podr\u00e1 recuperar la posesi\u00f3n de los PRODUCTOS, incluso desplaz\u00e1ndose hasta el lugar donde se encuentren almacenados. LA ORGANIZACI\u00d3N DE VENTAS podr\u00e1 demandar para obtener el pago antes de la transferencia de propiedad. El riesgo de p\u00e9rdida de los PRODUCTOS se transfiere al CLIENTE en el momento de la entrega de los PRODUCTOS. Despu\u00e9s de la entrega de los PRODUCTOS, el CLIENTE deber\u00e1 examinarlos dentro de los 8 (ocho) d\u00edas para comprobar si hay defectos o no conformidades. Transcurrido este plazo, los PRODUCTOS se entender\u00e1n aceptados por el CLIENTE. Si la ORGANIZACI\u00d3N DE VENTAS acepta entregar los PRODUCTOS, a su discreci\u00f3n y sin obligaci\u00f3n de ning\u00fan tipo, deber\u00e1n ser devueltos en su estado original, con el embalaje respectivo, comprobante de compra y con albar\u00e1n de devoluci\u00f3n de los bienes entregados. Los gastos de devoluci\u00f3n de la mercanc\u00eda ser\u00e1n a cargo del CLIENTE.<\/p>\n<p><strong>4. CAMBIOS EN LA CONSTRUCCI\u00d3N<\/strong><br \/>\nDebido a la constante evoluci\u00f3n de la tecnolog\u00eda, la racionalizaci\u00f3n de los procesos industriales y la variabilidad de los componentes constructivos determinada por los cambios en las fuentes de adquisici\u00f3n, los PRODUCTOS est\u00e1n sujetos a una evoluci\u00f3n continua, que puede implicar modificaciones en la construcci\u00f3n y pueden afectar a piezas electr\u00f3nicas y mec\u00e1nicas o a caracter\u00edsticas est\u00e9ticas de los PRODUCTOS (incluidos el tono de color y los elementos decorativos).<br \/>\nAsimismo, los datos informativos contenidos en folletos y documentos publicitarios en general no tienen car\u00e1cter vinculante y son meramente indicativos. Con excepci\u00f3n de las tolerancias permitidas por la ley o la costumbre, las caracter\u00edsticas t\u00e9cnicas de los PRODUCTOS certificados en el certificado de aprobaci\u00f3n son garantizadas por el FABRICANTE para cada instrumento producido, con su respectivo certificado de conformidad.<br \/>\nEn consideraci\u00f3n de lo anterior, el CLIENTE no podr\u00e1 rechazar el PRODUCTO puesto a disposici\u00f3n por la ORGANIZACI\u00d3N DE VENTAS para cumplir con el pedido.<\/p>\n<p><strong>5. GARANT\u00cdA DEL PRODUCTO<\/strong><br \/>\n5.1 HARDWARE: LA ORGANIZACI\u00d3N DE VENTAS garantiza el PRODUCTO contra vicios y defectos de fabricaci\u00f3n comprobados y reconocidos por la red de asistencia del FABRICANTE, durante un per\u00edodo de tiempo<\/p>\n<p>veinticuatro meses a partir de la fecha de entrega o activaci\u00f3n del software. Sin embargo, los t\u00e9rminos de la garant\u00eda pueden diferir para tipos espec\u00edficos de componentes y piezas de los PRODUCTOS. Estas diferentes condiciones de garant\u00eda ser\u00e1n comunicadas por escrito por el FABRICANTE y\/o estar\u00e1n disponibles\/accesibles en el programa de c\u00f3digo del \u00c1rea de Servicio reservada y\/o en el sitio web www.TEXA.it. La garant\u00eda consiste en la obligaci\u00f3n de la ORGANIZACI\u00d3N DE VENTAS y\/o centro de asistencia autorizado de restablecer la eficiencia funcional de los PRODUCTOS, mediante la sustituci\u00f3n o reparaci\u00f3n de piezas defectuosas sin coste alguno.<br \/>\nLa garant\u00eda no cubre defectos o mal funcionamiento debido a: a) mantenimiento insuficiente, calibraci\u00f3n err\u00f3nea, desgaste normal, accidentes causados \u200b\u200bpor terceros, instalaci\u00f3n el\u00e9ctrica incorrecta, transformaci\u00f3n, modificaci\u00f3n, manipulaci\u00f3n, montaje o desmontaje incorrecto, almacenamiento inadecuado; b) software, hardware, interfaz y cualquier otro componente ensamblado utilizado con los PRODUCTOS TEXA, pero no proporcionado por la red oficial de ventas y asistencia del FABRICANTE; c) modificaciones no autorizadas o uso que no cumpla con el uso previsto; d) uso de PRODUCTOS en un entorno que no cumple con los requisitos especificados para el PRODUCTO; e) incorrecta preparaci\u00f3n o mantenimiento del ambiente donde se utilizan los PRODUCTOS.<br \/>\n5.2 SOFTWARE:\u00a0Aunque el FABRICANTE ha tomado todas las precauciones posibles para garantizar la exactitud de la informaci\u00f3n contenida y visualizada en el software, no puede garantizar que el software o cualquier informaci\u00f3n contenida y visualizada en \u00e9l cumpla con los requisitos del CLIENTE, est\u00e9 libre de errores, funcione indefinidamente y que cualquier defecto en el software puede corregirse.<br \/>\n5.3 UBICACI\u00d3N DONDE SE PROPORCIONA EL SERVICIO BAJO LA GARANT\u00cdA:\u00a0Todas las reparaciones en garant\u00eda, a menos que se acuerde lo contrario por escrito, deben realizarse en las instalaciones del FABRICANTE o en el centro de servicio autorizado del FABRICANTE. Todos los gastos incurridos en el transporte del PRODUCTO a reparar desde las instalaciones del CLIENTE hasta el centro de asistencia y\/o por el desplazamiento del personal de asistencia del FABRICANTE o desde el centro de asistencia hasta las instalaciones del CLIENTE ser\u00e1n por cuenta del CLIENTE.<br \/>\n5.4 TRANSPORTE:\u00a0La garant\u00eda no cubre los da\u00f1os sufridos durante el transporte y las roturas por embalaje inadecuado realizado por el CLIENTE en el caso de que la mercanc\u00eda se entregue para su reparaci\u00f3n.<\/p>\n<p><strong>6. MANTENIMIENTO<\/strong><br \/>\nAntes de la entrega al CLIENTE, el PRODUCTO es probado por el FABRICANTE y la ORGANIZACI\u00d3N DE VENTAS (si est\u00e1 programado). Sin embargo, los PRODUCTOS siempre requieren mantenimiento (como, por ejemplo, inspecci\u00f3n de los filtros de condensaci\u00f3n y de gases en el producto \u00abanalizador de gases\u00bb, de la c\u00e1mara de humos en el producto \u00abopameter\u00bb, de la carga de la bater\u00eda en PRODUCTOS port\u00e1tiles, etc.). El derecho al servicio de garant\u00eda quedar\u00e1 anulado si no se llevan a cabo todas las intervenciones m\u00ednimas de mantenimiento enumeradas en el manual de usuario suministrado con el PRODUCTO.<\/p>\n<p><strong>7. LICENCIA DE SOFTWARE<\/strong><br \/>\n<strong>El FABRICANTE<\/strong> otorga al CLIENTE el derecho a utilizar el software contenido en los PRODUCTOS adquiridos, en base a un acuerdo de licencia de usuario no exclusivo y para los fines exclusivos descritos en el manual de usuario del PRODUCTO. A los efectos del acuerdo de licencia de usuario, \u00absoftware\u00bb se refiere al programa instalado en el PRODUCTO y \u00ablicencia\u00bb se refiere al derecho a usar o acceder a una copia particular del software espec\u00edfico.<br \/>\nEl CLIENTE licenciado deber\u00e1 conservar el contrato de licencia como prueba de su derecho a utilizar el software, otorgado por el fabricante licenciante. Si el CLIENTE licenciatario no acepta los t\u00e9rminos del contrato de licencia de uso, deber\u00e1 devolver inmediatamente el PRODUCTO que contiene el software a la ORGANIZACI\u00d3N DE VENTAS, junto con el material y documentaci\u00f3n aportados.<br \/>\nEl software instalado en el PRODUCTO es propiedad intelectual del FABRICANTE y sus proveedores. La estructura, organizaci\u00f3n y c\u00f3digo del software constituyen importantes secretos industriales y son informaci\u00f3n confidencial propiedad del FABRICANTE y sus proveedores. El software est\u00e1 protegido por leyes de derechos de autor, as\u00ed como por otras leyes y tratados internacionales de propiedad intelectual. El CLIENTE s\u00f3lo podr\u00e1 utilizar una copia del software por cada licencia de usuario adquirida, o una versi\u00f3n anterior del software para el mismo sistema operativo.<br \/>\nEL CLIENTE tiene prohibido:<br \/>\nA) Alquilar, transferir, otorgar sublicencias, prestar, copiar, modificar, reproducir, traducir, redise\u00f1ar, descomponer o desensamblar el software obtenido con la licencia de usuario, o la informaci\u00f3n contenida en el mismo.<br \/>\nB) Transmitir el software o cualquier parte del mismo por cable, ether o cualquier otro medio.<br \/>\nC) Crear obras o derivar otras, bas\u00e1ndose, incluso parcialmente, en el software o en la informaci\u00f3n contenida en \u00e9l o asociada a \u00e9l.<br \/>\nD) Utilizar, reproducir, imprimir o comercializar el software o la informaci\u00f3n contenida de forma no prevista en este contrato.<br \/>\nEl acuerdo de licencia de usuario es v\u00e1lido hasta el final del acuerdo de usuario del software.<\/p>\n<p>El contrato finalizar\u00e1 con la destrucci\u00f3n del software y su documentaci\u00f3n. Despu\u00e9s de su uso, el CLIENTE se compromete a destruir todas las copias del software, ya sea almacenadas en una tarjeta de memoria, CD-ROM, Disco Duro o cualquier otro soporte de memoria, junto con la documentaci\u00f3n respectiva.<br \/>\nLos derechos y obligaciones contenidos en el contrato de licencia de usuario no pueden transferirse ni transferirse a terceros sin el consentimiento por escrito del FABRICANTE.<br \/>\nEl software es instalado y utilizado por el CLIENTE bajo su propio riesgo y el FABRICANTE no se hace responsable, bajo ninguna circunstancia, de cualquier p\u00e9rdida o da\u00f1o, incluido el lucro cesante u otras p\u00e9rdidas debido al uso o la imposibilidad de utilizar el software en asociaci\u00f3n con cualquier otro programa.<br \/>\nEs responsabilidad del CLIENTE controlar la posible presencia de virus inform\u00e1ticos en los PRODUCTOS donde est\u00e9 instalado el software. EL FABRICANTE no se hace responsable de p\u00e9rdidas, da\u00f1os o costos de cualquier tipo causados \u200b\u200bpor la presencia de un virus.<\/p>\n<p><strong>8. RESPONSABILIDADES<\/strong><br \/>\n<strong>El CLIENTE<\/strong> es responsable del uso de cualquier instrumento y programa de software puesto a disposici\u00f3n por el FABRICANTE y vendido por la ORGANIZACI\u00d3N DE VENTAS. El CLIENTE se compromete a indemnizar al FABRICANTE y a la ORGANIZACI\u00d3N DE VENTAS y eximirlos de cualquier da\u00f1o causado por el uso inadecuado de los PRODUCTOS (incluido el software) vendidos por la ORGANIZACI\u00d3N DE VENTAS y adquiridos por el CLIENTE y el uso de los PRODUCTOS en violaci\u00f3n de las instrucciones contenidas. en programas y manuales de usuario.<br \/>\nEl CLIENTE deber\u00e1 utilizar todos los datos e informaci\u00f3n obtenidos por el FABRICANTE o la ORGANIZACI\u00d3N DE VENTAS directamente o a trav\u00e9s de programas y manuales de usuario, consciente de que dichos datos no siempre pueden ser exhaustivos y siempre deben utilizarse como una integraci\u00f3n del propio conocimiento profesional.<\/p>\n<p><strong>9. TRANSFERENCIA DEL CONTRATO<\/strong><br \/>\nEn caso de terminaci\u00f3n, por cualquier motivo, de la relaci\u00f3n contractual entre la ORGANIZACI\u00d3N DE VENTAS autorizada y el centro de soporte de productos TEXA, se otorgar\u00e1 irrevocablemente a TEXA el derecho de designar otra ORGANIZACI\u00d3N DE VENTAS autorizada TEXA, que asumir\u00e1 este contrato. Esta transferencia entrar\u00e1 en vigor en la fecha de su comunicaci\u00f3n al CLIENTE. La ORGANIZACI\u00d3N DE VENTAS seguir\u00e1 siendo propietaria de todos los derechos y obligaciones que surjan a partir de la fecha de la transferencia.<br \/>\nAl ejecutar este Acuerdo, el CLIENTE acepta la transferencia de este Acuerdo de la ORGANIZACI\u00d3N DE VENTAS a TEXA u otra organizaci\u00f3n de ventas autorizada designada por TEXA.<\/p>\n<p><strong>10. FUERZA MAYOR<\/strong><br \/>\nLos retrasos en el cumplimiento de las obligaciones contractuales podr\u00e1n justificarse por hechos que retrasen el proceso de fabricaci\u00f3n, distribuci\u00f3n o reparaci\u00f3n, tales como suspensi\u00f3n de trabajos, disturbios sindicales, capacidad de producci\u00f3n sobrevenida e imprevista del FABRICANTE, suspensi\u00f3n de servicios de transporte o suministro de energ\u00eda, disposiciones decretadas por el Administraci\u00f3n P\u00fablica, calamidades naturales u otras causas de fuerza mayor o caso fortuito, que puedan ocurrir en las instalaciones del FABRICANTE o de sus proveedores, durante el transporte o en las instalaciones de la ORGANIZACI\u00d3N DE VENTAS.<\/p>\n<p><strong>11. CONFIDENCIALIDAD Y OBLIGACIONES DEL CLIENTE<\/strong><br \/>\nAmbas Partes se comprometen a mantener la informaci\u00f3n de car\u00e1cter t\u00e9cnico y comercial, intercambiada en el \u00e1mbito de este contrato de venta o durante la fase de preparaci\u00f3n del contrato, como estrictamente confidencial, y a abstenerse de revelar dicha informaci\u00f3n a terceros sin la autorizaci\u00f3n previa por escrito de la otra. Fiesta. Esta obligaci\u00f3n continuar\u00e1, sin l\u00edmite temporal, y por tanto hasta sucesivamente hasta la extinci\u00f3n del citado Contrato con la ORGANIZACI\u00d3N DE VENTAS.<br \/>\nEl CLIENTE tambi\u00e9n se compromete a no adquirir los PRODUCTOS como representante, agente o abogado de competidores del FABRICANTE.<\/p>\n<p><strong>12. INFORMACI\u00d3N SOBRE EL TRATAMIENTO DE DATOS PERSONALES DE ACUERDO CON EL REGLAMENTO UE N. 2016\/679<\/strong><br \/>\nDe conformidad con los art\u00edculos 13 y 14 del Reglamento UE n. 2016\/679, le informamos que los datos personales proporcionados por el CLIENTE ser\u00e1n tratados por la ORGANIZACI\u00d3N DE VENTAS y el FABRICANTE en formato impreso, tecnolog\u00edas de la informaci\u00f3n y telem\u00e1tica, para las siguientes finalidades:<br \/>\n1. Por exigencias contractuales y legales;<br \/>\n2. Para an\u00e1lisis de mercado, actividades de marketing, estad\u00edsticas y para una gesti\u00f3n comercial eficaz;<br \/>\n3. Enviar materiales publicitarios y promocionales a trav\u00e9s de sistemas de correo electr\u00f3nico o SMS, relacionados con futuras iniciativas comerciales y anunciar nuevos productos, servicios y ofertas, incluso de terceros, relacionados con el sector de la automoci\u00f3n y el transporte.<br \/>\nRespecto a las finalidades indicadas en el apartado a), queremos precisar que la naturaleza de la atribuci\u00f3n de sus datos es obligatoria por ley, cuando una posible negativa imposibilite la ejecuci\u00f3n del presente contrato, mientras que para las finalidades indicadas en<\/p>\n<p>apartados b) yc), la naturaleza de la atribuci\u00f3n es electiva, por lo que solicitamos su consentimiento espec\u00edfico, con la especificaci\u00f3n de que cualquier negativa del consentimiento no tendr\u00e1 consecuencias<\/p>\n<p>actividades cubiertas por este contrato. Mientras persistan las comunicaciones y divulgaciones realizadas en cumplimiento de obligaciones legales y contractuales, los datos se comunicar\u00e1n en Italia, para los fines indicados anteriormente, a las siguientes partes externas: instituciones de cr\u00e9dito y otros intermediarios financieros, para cumplimientos relacionados con la relaci\u00f3n comercial. (por ejemplo, pagos), profesionales, consultores y proveedores de servicios y, eventualmente, a bufetes de abogados y empresas de recuperaci\u00f3n de cr\u00e9ditos. Tendr\u00e1 la opci\u00f3n de ejercer sus derechos en virtud de los art\u00edculos 15 a 22 del Reglamento de la UE no. 2016\/679 enviando una solicitud especial por escrito a la direcci\u00f3n de correo electr\u00f3nico:\u00a0privacy@texa.com, as\u00ed como un derecho de reclamaci\u00f3n ante la Autoridad de Privacidad para la protecci\u00f3n de datos personales (Art\u00edculo 77 del Reglamento UE No. 2016\/679).<br \/>\nEl propietario del tratamiento es<\/p>\n<p>TEXA S.p.A.<br \/>\nSede: Via 1 Maggio, 9 &#8211; 31050 Monastier di Treviso &#8211; ITALIA<br \/>\nSede administrativa y f\u00e1brica: Via Vallio &#8211; 31050 Monastier di Treviso &#8211; ITALIA<\/p>\n<p><strong>13. CONTRATOS COMPLEMENTARIOS<\/strong><br \/>\nCualquier acuerdo adicional o hecho como excepci\u00f3n a estas condiciones de venta s\u00f3lo ser\u00e1 vinculante si se estipula por escrito.<br \/>\nEl CLIENTE reconoce que la ORGANIZACI\u00d3N DE VENTAS no tiene poderes de representaci\u00f3n del FABRICANTE.<\/p>\n<p><strong>14. TRIBUNAL COMPETENTE<\/strong><br \/>\nEste Acuerdo se regir\u00e1 por la ley italiana y el tribunal exclusivamente competente ser\u00e1 el distrito en el que la ORGANIZACI\u00d3N DE VENTAS tenga su sede legal.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-726cdcd elementor-widget elementor-widget-spacer\" data-id=\"726cdcd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1. DEFINICIONES FABRICANTE: el FABRICANTE es TEXA SpA. ORGANIZACI\u00d3N DE VENTAS: la parte que vende los PRODUCTOS al CLIENTE. FABRICANTE y ORGANIZACI\u00d3N DE VENTAS pueden coincidir CLIENTE: la parte que compra los PRODUCTOS a la ORGANIZACI\u00d3N DE VENTAS. PRODUCTOS: aquellos comercializados por la ORGANIZACI\u00d3N DE VENTAS e indicados en las CONDICIONES PARTICULARES. En cualquier caso, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1058,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-25870","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Condiciones generales de venta - TEXA do Brasil<\/title>\n<meta name=\"description\" content=\"Conozca las condiciones generales de venta de los productos propios de TEXA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condiciones generales de venta - TEXA do Brasil\" \/>\n<meta property=\"og:description\" content=\"Conozca las condiciones generales de venta de los productos propios de TEXA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/\" \/>\n<meta property=\"og:site_name\" content=\"TEXA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/texabrasil\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T14:47:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.texabrasil.com.br\/wp-content\/uploads\/2019\/11\/TEXA-Azienda2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/\",\"url\":\"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/\",\"name\":\"Condiciones generales de venta - TEXA do Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www.texabrasil.com.br\/#website\"},\"datePublished\":\"2020-11-16T18:38:42+00:00\",\"dateModified\":\"2024-08-07T14:47:38+00:00\",\"description\":\"Conozca las condiciones generales de venta de los productos propios de TEXA.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.texabrasil.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condiciones generales de venta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.texabrasil.com.br\/#website\",\"url\":\"https:\/\/www.texabrasil.com.br\/\",\"name\":\"TEXA do Brasil\",\"description\":\"for automotive professionals\",\"publisher\":{\"@id\":\"https:\/\/www.texabrasil.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.texabrasil.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.texabrasil.com.br\/#organization\",\"name\":\"TEXA do Brasil - Diagn\u00f3stico multimarcas e recicladoras de A\/C\",\"url\":\"https:\/\/www.texabrasil.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.texabrasil.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.texabrasil.com.br\/wp-content\/uploads\/2019\/11\/logo-TEXA.jpg\",\"contentUrl\":\"https:\/\/www.texabrasil.com.br\/wp-content\/uploads\/2019\/11\/logo-TEXA.jpg\",\"width\":300,\"height\":300,\"caption\":\"TEXA do Brasil - Diagn\u00f3stico multimarcas e recicladoras de A\/C\"},\"image\":{\"@id\":\"https:\/\/www.texabrasil.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/texabrasil\",\"https:\/\/www.instagram.com\/texabrasil\/\",\"https:\/\/www.linkedin.com\/company\/texabrasil\/\",\"https:\/\/www.youtube.com\/texabrasil\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condiciones generales de venta - TEXA do Brasil","description":"Conozca las condiciones generales de venta de los productos propios de TEXA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/","og_locale":"es_ES","og_type":"article","og_title":"Condiciones generales de venta - TEXA do Brasil","og_description":"Conozca las condiciones generales de venta de los productos propios de TEXA.","og_url":"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/","og_site_name":"TEXA","article_publisher":"https:\/\/www.facebook.com\/texabrasil","article_modified_time":"2024-08-07T14:47:38+00:00","og_image":[{"width":1920,"height":1265,"url":"https:\/\/www.texabrasil.com.br\/wp-content\/uploads\/2019\/11\/TEXA-Azienda2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/","url":"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/","name":"Condiciones generales de venta - TEXA do Brasil","isPartOf":{"@id":"https:\/\/www.texabrasil.com.br\/#website"},"datePublished":"2020-11-16T18:38:42+00:00","dateModified":"2024-08-07T14:47:38+00:00","description":"Conozca las condiciones generales de venta de los productos propios de TEXA.","breadcrumb":{"@id":"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.texabrasil.com.br\/general-condition-of-sale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.texabrasil.com.br\/"},{"@type":"ListItem","position":2,"name":"Condiciones generales de venta"}]},{"@type":"WebSite","@id":"https:\/\/www.texabrasil.com.br\/#website","url":"https:\/\/www.texabrasil.com.br\/","name":"TEXA do Brasil","description":"for automotive professionals","publisher":{"@id":"https:\/\/www.texabrasil.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.texabrasil.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.texabrasil.com.br\/#organization","name":"TEXA do Brasil - Diagn\u00f3stico multimarcas e recicladoras de A\/C","url":"https:\/\/www.texabrasil.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.texabrasil.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.texabrasil.com.br\/wp-content\/uploads\/2019\/11\/logo-TEXA.jpg","contentUrl":"https:\/\/www.texabrasil.com.br\/wp-content\/uploads\/2019\/11\/logo-TEXA.jpg","width":300,"height":300,"caption":"TEXA do Brasil - Diagn\u00f3stico multimarcas e recicladoras de A\/C"},"image":{"@id":"https:\/\/www.texabrasil.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/texabrasil","https:\/\/www.instagram.com\/texabrasil\/","https:\/\/www.linkedin.com\/company\/texabrasil\/","https:\/\/www.youtube.com\/texabrasil"]}]}},"_links":{"self":[{"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/pages\/25870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/comments?post=25870"}],"version-history":[{"count":0,"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/pages\/25870\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/media?parent=25870"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.texabrasil.com.br\/es\/wp-json\/wp\/v2\/tags?post=25870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}